{"id":21,"date":"2025-06-01T12:00:47","date_gmt":"2025-06-01T16:00:47","guid":{"rendered":"https:\/\/experthive.hivepress.io\/?page_id=21"},"modified":"2025-06-04T18:14:04","modified_gmt":"2025-06-04T22:14:04","slug":"requests","status":"publish","type":"page","link":"https:\/\/out4biz.org\/marketplace\/requests\/","title":{"rendered":"Requests"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"nf_dc_page":"","_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"class_list":["post-21","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Requests - OUT4BIZ Marketplace<\/title>\n<meta name=\"description\" content=\"Post your request, and connect with skilled professionals ready to assist\u2014whether for payment or trade..\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/out4biz.org\/marketplace\/requests\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Requests - OUT4BIZ Marketplace\" \/>\n<meta property=\"og:description\" content=\"Post your request, and connect with skilled professionals ready to assist\u2014whether for payment or trade..\" \/>\n<meta property=\"og:url\" content=\"https:\/\/out4biz.org\/marketplace\/requests\/\" \/>\n<meta property=\"og:site_name\" content=\"OUT4BIZ Marketplace\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-04T22:14:04+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/out4biz.org\\\/marketplace\\\/requests\\\/\",\"url\":\"https:\\\/\\\/out4biz.org\\\/marketplace\\\/requests\\\/\",\"name\":\"Requests - OUT4BIZ Marketplace\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/out4biz.org\\\/marketplace\\\/#website\"},\"datePublished\":\"2025-06-01T16:00:47+00:00\",\"dateModified\":\"2025-06-04T22:14:04+00:00\",\"description\":\"Post your request, and connect with skilled professionals ready to assist\u2014whether for payment or trade..\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/out4biz.org\\\/marketplace\\\/requests\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/out4biz.org\\\/marketplace\\\/requests\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/out4biz.org\\\/marketplace\\\/requests\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/out4biz.org\\\/marketplace\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Requests\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/out4biz.org\\\/marketplace\\\/#website\",\"url\":\"https:\\\/\\\/out4biz.org\\\/marketplace\\\/\",\"name\":\"out4biz.ca\",\"description\":\"2SLGBTQIA+ Entrepreneurs\",\"publisher\":{\"@id\":\"https:\\\/\\\/out4biz.org\\\/marketplace\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/out4biz.org\\\/marketplace\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/out4biz.org\\\/marketplace\\\/#organization\",\"name\":\"out4biz.ca\",\"url\":\"https:\\\/\\\/out4biz.org\\\/marketplace\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/out4biz.org\\\/marketplace\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/out4biz.org\\\/marketplace\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-Logo-OUT4BIZ29-small.png\",\"contentUrl\":\"https:\\\/\\\/out4biz.org\\\/marketplace\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-Logo-OUT4BIZ29-small.png\",\"width\":249,\"height\":84,\"caption\":\"out4biz.ca\"},\"image\":{\"@id\":\"https:\\\/\\\/out4biz.org\\\/marketplace\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.meetup.com\\\/out4biz\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Requests - OUT4BIZ Marketplace","description":"Post your request, and connect with skilled professionals ready to assist\u2014whether for payment or trade..","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/out4biz.org\/marketplace\/requests\/","og_locale":"en_US","og_type":"article","og_title":"Requests - OUT4BIZ Marketplace","og_description":"Post your request, and connect with skilled professionals ready to assist\u2014whether for payment or trade..","og_url":"https:\/\/out4biz.org\/marketplace\/requests\/","og_site_name":"OUT4BIZ Marketplace","article_modified_time":"2025-06-04T22:14:04+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/out4biz.org\/marketplace\/requests\/","url":"https:\/\/out4biz.org\/marketplace\/requests\/","name":"Requests - OUT4BIZ Marketplace","isPartOf":{"@id":"https:\/\/out4biz.org\/marketplace\/#website"},"datePublished":"2025-06-01T16:00:47+00:00","dateModified":"2025-06-04T22:14:04+00:00","description":"Post your request, and connect with skilled professionals ready to assist\u2014whether for payment or trade..","breadcrumb":{"@id":"https:\/\/out4biz.org\/marketplace\/requests\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/out4biz.org\/marketplace\/requests\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/out4biz.org\/marketplace\/requests\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/out4biz.org\/marketplace\/"},{"@type":"ListItem","position":2,"name":"Requests"}]},{"@type":"WebSite","@id":"https:\/\/out4biz.org\/marketplace\/#website","url":"https:\/\/out4biz.org\/marketplace\/","name":"out4biz.ca","description":"2SLGBTQIA+ Entrepreneurs","publisher":{"@id":"https:\/\/out4biz.org\/marketplace\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/out4biz.org\/marketplace\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/out4biz.org\/marketplace\/#organization","name":"out4biz.ca","url":"https:\/\/out4biz.org\/marketplace\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/out4biz.org\/marketplace\/#\/schema\/logo\/image\/","url":"https:\/\/out4biz.org\/marketplace\/wp-content\/uploads\/2025\/05\/cropped-Logo-OUT4BIZ29-small.png","contentUrl":"https:\/\/out4biz.org\/marketplace\/wp-content\/uploads\/2025\/05\/cropped-Logo-OUT4BIZ29-small.png","width":249,"height":84,"caption":"out4biz.ca"},"image":{"@id":"https:\/\/out4biz.org\/marketplace\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.meetup.com\/out4biz"]}]}},"_links":{"self":[{"href":"https:\/\/out4biz.org\/marketplace\/wp-json\/wp\/v2\/pages\/21","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/out4biz.org\/marketplace\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/out4biz.org\/marketplace\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/out4biz.org\/marketplace\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/out4biz.org\/marketplace\/wp-json\/wp\/v2\/comments?post=21"}],"version-history":[{"count":1,"href":"https:\/\/out4biz.org\/marketplace\/wp-json\/wp\/v2\/pages\/21\/revisions"}],"predecessor-version":[{"id":930,"href":"https:\/\/out4biz.org\/marketplace\/wp-json\/wp\/v2\/pages\/21\/revisions\/930"}],"wp:attachment":[{"href":"https:\/\/out4biz.org\/marketplace\/wp-json\/wp\/v2\/media?parent=21"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}